{"id":321,"date":"2026-03-23T19:02:43","date_gmt":"2026-03-23T18:02:43","guid":{"rendered":"https:\/\/midsa.es\/nueva\/la-clinica\/"},"modified":"2026-07-15T19:27:07","modified_gmt":"2026-07-15T17:27:07","slug":"the-clinic","status":"publish","type":"page","link":"https:\/\/midsa.es\/en\/la-clinica\/","title":{"rendered":"The Clinic"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-321","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Cl\u00ednica Dental en Valencia &#8212; MIDSA<\/title>\n<meta name=\"description\" content=\"Cl\u00ednica dental en Valencia. Odontolog\u00eda avanzada con trato cercano, diagn\u00f3stico digital y atenci\u00f3n honesta desde la primera visita.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/midsa.es\/en\/the-clinic\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Cl\u00ednica Dental en Valencia &#8212; MIDSA\" \/>\n<meta property=\"og:description\" content=\"Cl\u00ednica dental en Valencia. Odontolog\u00eda avanzada con trato cercano, diagn\u00f3stico digital y atenci\u00f3n honesta desde la primera visita.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/midsa.es\/en\/the-clinic\/\" \/>\n<meta property=\"og:site_name\" content=\"MIDSA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/midsaodontologiavalencia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T17:27:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/midsa.es\/wp-content\/uploads\/2026\/04\/logo-midsa-web.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/midsa.es\\\/la-clinica\\\/\",\"url\":\"https:\\\/\\\/midsa.es\\\/la-clinica\\\/\",\"name\":\"La Cl\u00ednica Dental en Valencia &#8212; MIDSA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/midsa.es\\\/#website\"},\"datePublished\":\"2026-03-23T18:02:43+00:00\",\"dateModified\":\"2026-07-15T17:27:07+00:00\",\"description\":\"Cl\u00ednica dental en Valencia. Odontolog\u00eda avanzada con trato cercano, diagn\u00f3stico digital y atenci\u00f3n honesta desde la primera visita.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/midsa.es\\\/la-clinica\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/midsa.es\\\/la-clinica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/midsa.es\\\/la-clinica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/midsa.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Cl\u00ednica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/midsa.es\\\/#website\",\"url\":\"https:\\\/\\\/midsa.es\\\/\",\"name\":\"Midsa Odontolog\u00eda & Co\",\"description\":\"Somos MIDSA, Cl&iacute;nica Dental en Valencia. Odontolog&iacute;a avanzada con trato cercano en el coraz&oacute;n de Valencia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/midsa.es\\\/#organization\"},\"alternateName\":\"Midsa Odontolog\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/midsa.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/midsa.es\\\/#organization\",\"name\":\"Midsa Odontolog\u00eda & Co\",\"alternateName\":\"Midsa Odontolog\u00eda\",\"url\":\"https:\\\/\\\/midsa.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/midsa.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/midsa.es\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo_midsa.png\",\"contentUrl\":\"https:\\\/\\\/midsa.es\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo_midsa.png\",\"width\":1080,\"height\":361,\"caption\":\"Midsa Odontolog\u00eda & Co\"},\"image\":{\"@id\":\"https:\\\/\\\/midsa.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/midsaodontologiavalencia\",\"https:\\\/\\\/www.instagram.com\\\/midsaodontologia\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Dental Clinic in Valencia \u2014 MIDSA","description":"Dental clinic in Valencia. Advanced dentistry with a personal touch, digital diagnosis, and honest care from the first visit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/midsa.es\/en\/the-clinic\/","og_locale":"en_GB","og_type":"article","og_title":"La Cl\u00ednica Dental en Valencia &#8212; MIDSA","og_description":"Cl\u00ednica dental en Valencia. Odontolog\u00eda avanzada con trato cercano, diagn\u00f3stico digital y atenci\u00f3n honesta desde la primera visita.","og_url":"https:\/\/midsa.es\/en\/the-clinic\/","og_site_name":"MIDSA","article_publisher":"https:\/\/www.facebook.com\/midsaodontologiavalencia","article_modified_time":"2026-07-15T17:27:07+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/midsa.es\/wp-content\/uploads\/2026\/04\/logo-midsa-web.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/midsa.es\/la-clinica\/","url":"https:\/\/midsa.es\/la-clinica\/","name":"The Dental Clinic in Valencia \u2014 MIDSA","isPartOf":{"@id":"https:\/\/midsa.es\/#website"},"datePublished":"2026-03-23T18:02:43+00:00","dateModified":"2026-07-15T17:27:07+00:00","description":"Dental clinic in Valencia. Advanced dentistry with a personal touch, digital diagnosis, and honest care from the first visit.","breadcrumb":{"@id":"https:\/\/midsa.es\/la-clinica\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/midsa.es\/la-clinica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/midsa.es\/la-clinica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/midsa.es\/"},{"@type":"ListItem","position":2,"name":"La Cl\u00ednica"}]},{"@type":"WebSite","@id":"https:\/\/midsa.es\/#website","url":"https:\/\/midsa.es\/","name":"Midsa Dentistry &amp; Co","description":"We are MIDSA, a dental clinic in Valencia. Advanced dentistry with personalized service in the heart of Valencia.","publisher":{"@id":"https:\/\/midsa.es\/#organization"},"alternateName":"Midsa Odontolog\u00eda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/midsa.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/midsa.es\/#organization","name":"Midsa Dentistry &amp; Co","alternateName":"Midsa Odontolog\u00eda","url":"https:\/\/midsa.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/midsa.es\/#\/schema\/logo\/image\/","url":"https:\/\/midsa.es\/wp-content\/uploads\/2026\/03\/logo_midsa.png","contentUrl":"https:\/\/midsa.es\/wp-content\/uploads\/2026\/03\/logo_midsa.png","width":1080,"height":361,"caption":"Midsa Odontolog\u00eda & Co"},"image":{"@id":"https:\/\/midsa.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/midsaodontologiavalencia","https:\/\/www.instagram.com\/midsaodontologia\/"]}]}},"_links":{"self":[{"href":"https:\/\/midsa.es\/en\/wp-json\/wp\/v2\/pages\/321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/midsa.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/midsa.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/midsa.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/midsa.es\/en\/wp-json\/wp\/v2\/comments?post=321"}],"version-history":[{"count":9,"href":"https:\/\/midsa.es\/en\/wp-json\/wp\/v2\/pages\/321\/revisions"}],"predecessor-version":[{"id":823,"href":"https:\/\/midsa.es\/en\/wp-json\/wp\/v2\/pages\/321\/revisions\/823"}],"wp:attachment":[{"href":"https:\/\/midsa.es\/en\/wp-json\/wp\/v2\/media?parent=321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}